{"id":2410,"date":"2022-04-06T14:10:59","date_gmt":"2022-04-06T14:10:59","guid":{"rendered":"http:\/\/www.puertocdelu.com.ar\/?p=2410"},"modified":"2022-04-06T14:10:59","modified_gmt":"2022-04-06T14:10:59","slug":"ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies","status":"publish","type":"post","link":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/","title":{"rendered":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies"},"content":{"rendered":"<p>Se reuni\u00f3 el Comit\u00e9 de Cuenca del R\u00edo Uruguay. Autoridades y representantes de 25 ciudades argentinas, uruguayas y brasile\u00f1as impulsan gestiones para unificar el dragado del r\u00edo a 34 pies con el objetivo de potenciar el desarrollo, la producci\u00f3n y la industria de la regi\u00f3n.<\/p>\n<div>El encuentro tuvo lugar en la sede de la Comisi\u00f3n Administradora del R\u00edo Uruguay (CARU), y cont\u00f3 con la participaci\u00f3n de representantes de ciudades de los tres pa\u00edses, gobiernos provinciales y autoridades nacionales, tanto de forma presencial, como virtual. Estuvo encabezado por Omar Lafluf, intendente del departamento R\u00edo Negro (ROU), y actual presidente del Comit\u00e9, el subsecretario de Puertos y V\u00edas Navegables de la Naci\u00f3n, Leonardo Cabrera, el Presidente del Instituto Portuario Provincial de Entre R\u00edos, Carlos Schepens, el intendente de Concepci\u00f3n del Uruguay, Mart\u00edn Oliva, y los presidentes de las delegaciones argentina y uruguaya de CARU, Jos\u00e9 Lauritto y Daniel Ayala, respectivamente.Tambi\u00e9n formaron parte de la mesa la Corporaci\u00f3n para el Desarrollo de Gualeguaych\u00fa (Codegu), encabezados por su presidenta, Estela Mi\u00f1o, y el Prefecto Naval de Uruguay, Jos\u00e9 Luis Elizondo.<\/p>\n<p>En ese marco, Lafluf resalt\u00f3 que \u201ccon el gobernador de Entre R\u00edos, Gustavo Bordet, nos une una gran amistad y el convencimiento de que debemos desarrollarnos como regi\u00f3n poniendo el bienestar de nuestra gente como prioridad absoluta. Desde este Comit\u00e9 hoy afirmo que es vital para toda nuestra regi\u00f3n contar con un dragado a 34 pies para los puertos de Concepci\u00f3n del Uruguay, Fray Bentos y Paysand\u00fa\u201d, enfatiz\u00f3.<\/p>\n<p>Adem\u00e1s, detall\u00f3 que \u201cpara poder crecer y desarrollarnos tenemos muy pocas variables que se puedan tocar para bajar costos. La \u00fanica alternativa que nos queda para desarrollarnos es ser competitivos en la log\u00edstica, y sin un dragado a 34 pies es imposible ser competitivos porque los buques que exportan nuestros productos no pueden completar sus bodegas y duplican o triplican los costos para llegar a nuestros puertos y exportar nuestra producci\u00f3n\u201d.<\/p>\n<\/div>\n<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-381607\" src=\"https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02.jpg\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" srcset=\"https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02.jpg 1920w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-300x200.jpg 300w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-1024x683.jpg 1024w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-768x512.jpg 768w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-1536x1024.jpg 1536w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-696x464.jpg 696w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/dragado02-1068x712.jpg 1068w\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/p>\n<p><b>Desarrollo portuario en Entre R\u00edos<br \/>\n<\/b><br \/>\nPor su parte, el presidente del Instituto Portuario de Entre R\u00edos, Carlos Schepens, sostuvo que \u201ces necesaria la complementariedad de las v\u00edas log\u00edsticas que necesita toda la regi\u00f3n para el crecimiento y el desarrollo de nuestras comunidades\u201d.<\/p>\n<p>\u201cLa hidrov\u00eda del r\u00edo Uruguay es complementaria con la del Paran\u00e1-Paraguay. Las cargas de la Mesopotamia, Paraguay, Bolivia, Uruguay, y el sur de Brasil necesitan y reclaman alternativas de salida al mundo, sobre todo cuando se presentan verdaderos problemas como los que representa, desde hace meses, la bajante del r\u00edo Paran\u00e1\u201d, expres\u00f3 el funcionario entrerriano.<\/p>\n<p>El presidente de los puertos provinciales remarc\u00f3 que \u201cEntre R\u00edos ha demostrado que es posible desarrollar una pol\u00edtica portuaria seria y con resultados a la vista. Ha puesto en marcha el transporte multimodal invirtiendo en sus puertos, reactivando el ferrocarril, sumando infraestructura. Hemos vuelto a sacar m\u00e1s de 60 ultramarinos de nuestros puertos con 2 millones de toneladas exportadas\u201d. En ese sentido, pidi\u00f3 avanzar para lograr \u201clas condiciones para que toda esta regi\u00f3n cuente con el r\u00edo Uruguay en condiciones de sumar ventajas, para que nuestros productores e industriales cuenten con puertos que les permitan crecer y generar trabajo genuino para nuestras comunidades\u201d.<\/p>\n<p>El intendente de Concepci\u00f3n del Uruguay, Mart\u00edn Oliva, tambi\u00e9n sostuvo que \u201ces impensable que una ciudad con puerto no pueda desarrollarse, nuestros productores lo demandan, y nuestros pueblos, nuestras comunidades lo necesitan. Si bien parece que hablamos s\u00f3lo de puertos y navegabilidad, en realidad de lo que hablamos es de trabajo para nuestra gente. El trabajo es la dignidad de cualquier ciudadano, as\u00ed que ah\u00ed est\u00e1 el punto central\u201d, se\u00f1al\u00f3 Oliva.<\/p>\n<p>El subsecretario de Puertos y V\u00edas Navegables de la Naci\u00f3n, Leonardo Cabrera, reiter\u00f3 \u201cel respaldo del Ministro de Transporte de la Naci\u00f3n, Alexis Guerrera con el desarrollo de los puertos de la regi\u00f3n. Junto al Gobernador Gustavo Bordet se realiz\u00f3 hace pocos meses un aporte de 2 millones de d\u00f3lares para la compra de una gr\u00faa para el puerto de Concepci\u00f3n del Uruguay. El objetivo es seguir sumando infraestructura para que los puertos de toda la Argentina ganen en competitividad y se puedan desarrollar las econom\u00edas regionales\u201d.<\/p>\n<\/div>\n<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-381608\" src=\"https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU.jpg\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" srcset=\"https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU.jpg 1920w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-300x200.jpg 300w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-1024x683.jpg 1024w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-768x512.jpg 768w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-1536x1024.jpg 1536w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-696x464.jpg 696w, https:\/\/03442.com.ar\/wp-content\/uploads\/2022\/04\/puerto-CdelU-1068x712.jpg 1068w\" alt=\"\" width=\"1920\" height=\"1280\" \/><\/p>\n<p><b>Una necesidad<br \/>\n<\/b><br \/>\nMarcelo Gay Balm\u00e1z, presidente del Ente Puerto Concepci\u00f3n del Uruguay, expuso sobre las ventajas para las exportaciones de la regi\u00f3n que representa un calado de 34 pies en el puerto de Concepci\u00f3n del Uruguay, y en las terminales uruguayas de Fray Bentos y Paysand\u00fa.<\/p>\n<p>Remarc\u00f3 que \u201clos puertos sobre el r\u00edo Uruguay estamos en riesgo de desaparecer si no nos adaptamos a las necesidades que impone el comercio internacional actual, con buques cada vez m\u00e1s grandes y con una ecuaci\u00f3n de costos que hace muy dif\u00edcil integrar nuestros puertos a las cadenas log\u00edsticas de las grandes empresas navieras\u201d.<\/p>\n<p>El presidente del puerto de Concepci\u00f3n del Uruguay afirm\u00f3 que \u201cnuestro desarrollo estrat\u00e9gico para poder seguir operando depende, absolutamente, de un calado que permita a los buques ingresar, cargar completos, y zarpar rumbo a su destino final. Hoy est\u00e1n cargando al 50 o 60 por ciento de su capacidad, y eso los obliga a tocar otros puertos para completar, sumando costos de 80 o 100 mil d\u00f3lares por viaje, costos que pagan los productores o industriales y que quita competitividad a la regi\u00f3n\u201d.<\/p>\n<p><b>Pedido a los gobiernos nacionales<br \/>\n<\/b><br \/>\nEl Comit\u00e9 para el Desarrollo de la Cuenca del R\u00edo Uruguay, resolvi\u00f3 interesar a los gobiernos nacionales de Argentina y Uruguay, sobre la necesidad de unificar la profundidad del r\u00edo Uruguay a 34 pies.<\/p>\n<\/div>\n<div class=\"td-a-rec td-a-rec-id-content_bottom  tdi_4 td_block_template_8\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se reuni\u00f3 el Comit\u00e9 de Cuenca del R\u00edo Uruguay. Autoridades y representantes de 25 ciudades argentinas, uruguayas y brasile\u00f1as impulsan gestiones para unificar el dragado del r\u00edo a 34 pies con el objetivo de potenciar el desarrollo, la producci\u00f3n y la industria de la regi\u00f3n. El encuentro tuvo lugar en la sede de la Comisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":{"0":"post-2410","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay\" \/>\n<meta property=\"og:description\" content=\"Se reuni\u00f3 el Comit\u00e9 de Cuenca del R\u00edo Uruguay. Autoridades y representantes de 25 ciudades argentinas, uruguayas y brasile\u00f1as impulsan gestiones para unificar el dragado del r\u00edo a 34 pies con el objetivo de potenciar el desarrollo, la producci\u00f3n y la industria de la regi\u00f3n. El encuentro tuvo lugar en la sede de la Comisi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/\" \/>\n<meta property=\"og:site_name\" content=\"Puerto de Concepci\u00f3n del Uruguay\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T14:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PuertoCdelU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PuertoCdelU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/\"},\"author\":{\"name\":\"PuertoCdelU\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/#\\\/schema\\\/person\\\/9d258b923b29bd5f47ca80d9c8cd72d1\"},\"headline\":\"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies\",\"datePublished\":\"2022-04-06T14:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/\"},\"wordCount\":966,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Dragado01.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/\",\"url\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/\",\"name\":\"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Dragado01.jpg\",\"datePublished\":\"2022-04-06T14:10:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/#\\\/schema\\\/person\\\/9d258b923b29bd5f47ca80d9c8cd72d1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Dragado01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Dragado01.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/2022\\\/04\\\/06\\\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/\",\"name\":\"Puerto de Concepci\u00f3n del Uruguay\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/#\\\/schema\\\/person\\\/9d258b923b29bd5f47ca80d9c8cd72d1\",\"name\":\"PuertoCdelU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g\",\"caption\":\"PuertoCdelU\"},\"url\":\"https:\\\/\\\/www.puertocdelu.com.ar\\\/index.php\\\/author\\\/hectordelos1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/","og_locale":"es_ES","og_type":"article","og_title":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay","og_description":"Se reuni\u00f3 el Comit\u00e9 de Cuenca del R\u00edo Uruguay. Autoridades y representantes de 25 ciudades argentinas, uruguayas y brasile\u00f1as impulsan gestiones para unificar el dragado del r\u00edo a 34 pies con el objetivo de potenciar el desarrollo, la producci\u00f3n y la industria de la regi\u00f3n. El encuentro tuvo lugar en la sede de la Comisi\u00f3n [&hellip;]","og_url":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/","og_site_name":"Puerto de Concepci\u00f3n del Uruguay","article_published_time":"2022-04-06T14:10:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg","type":"image\/jpeg"}],"author":"PuertoCdelU","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PuertoCdelU","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#article","isPartOf":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/"},"author":{"name":"PuertoCdelU","@id":"https:\/\/www.puertocdelu.com.ar\/#\/schema\/person\/9d258b923b29bd5f47ca80d9c8cd72d1"},"headline":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies","datePublished":"2022-04-06T14:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/"},"wordCount":966,"commentCount":0,"image":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/","url":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/","name":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies - Puerto de Concepci\u00f3n del Uruguay","isPartOf":{"@id":"https:\/\/www.puertocdelu.com.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#primaryimage"},"image":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg","datePublished":"2022-04-06T14:10:59+00:00","author":{"@id":"https:\/\/www.puertocdelu.com.ar\/#\/schema\/person\/9d258b923b29bd5f47ca80d9c8cd72d1"},"breadcrumb":{"@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#primaryimage","url":"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg","contentUrl":"https:\/\/www.puertocdelu.com.ar\/wp-content\/uploads\/2022\/04\/Dragado01.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.puertocdelu.com.ar\/index.php\/2022\/04\/06\/ciudades-argentinas-uruguayas-y-brasilenas-impulsan-el-dragado-del-rio-uruguay-a-34-pies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.puertocdelu.com.ar\/"},{"@type":"ListItem","position":2,"name":"Ciudades argentinas, uruguayas, y brasile\u00f1as impulsan el dragado del r\u00edo Uruguay a 34 pies"}]},{"@type":"WebSite","@id":"https:\/\/www.puertocdelu.com.ar\/#website","url":"https:\/\/www.puertocdelu.com.ar\/","name":"Puerto de Concepci\u00f3n del Uruguay","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puertocdelu.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.puertocdelu.com.ar\/#\/schema\/person\/9d258b923b29bd5f47ca80d9c8cd72d1","name":"PuertoCdelU","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99e38dea1727d397df18aced5ac6840012bb7f24c8570dcfafabb73086aed88c?s=96&d=mm&r=g","caption":"PuertoCdelU"},"url":"https:\/\/www.puertocdelu.com.ar\/index.php\/author\/hectordelos1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2410"}],"version-history":[{"count":1,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2410\/revisions"}],"predecessor-version":[{"id":2412,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2410\/revisions\/2412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2411"}],"wp:attachment":[{"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.puertocdelu.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}